{"id":4508,"date":"2016-07-20T09:44:13","date_gmt":"2016-07-20T09:44:13","guid":{"rendered":"https:\/\/www.delsofa.es\/informacion\/?p=4508"},"modified":"2017-02-22T12:55:18","modified_gmt":"2017-02-22T12:55:18","slug":"artica-distribuidor-delsofa-huesca","status":"publish","type":"post","link":"https:\/\/www.delsofa.es\/informacion\/artica-distribuidor-delsofa-huesca\/","title":{"rendered":"\u00c1rtica, distribuidor de Delsof\u00e1 en Huesca"},"content":{"rendered":"<p style=\"text-align: justify;\">NOTA: Esta tienda ya no pertenece a la red de distribuidores de Colchones.es. Aqu\u00ed puedes encontrar nuestras <a href=\"https:\/\/www.colchones.es\/tiendas-de-colchones-huesca.php\">tiendas f\u00edsicas en Huesca<\/a><\/p>\n<p style=\"text-align: justify;\">Este mes el viaje virtual para conocer las tiendas f\u00edsicas de Delsof\u00e1 nos lleva a la provincia de Huesca. En ella se encuentra <a href=\"https:\/\/www.delsofa.es\/tiendas-de-sofas-y-sillones-huesca\/muebles-alcubierre-almudevar.php\" target=\"_blank\">\u00c1rtica<\/a>, <strong>distribuidor autorizado donde puedes probar los sof\u00e1s<\/strong>, sof\u00e1s cama, chaise longue, sillones\u2026 a la venta en nuestra tienda online.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-4509 size-full\" title=\"\u00c1rtica, distribuidor de Delsof\u00e1 en Huesca\" src=\"https:\/\/www.delsofa.es\/informacion\/wp-content\/uploads\/2016\/07\/fachada-artica.jpg\" alt=\"\u00c1rtica, distribuidor de Delsof\u00e1 en Huesca\" width=\"584\" height=\"262\" srcset=\"https:\/\/www.delsofa.es\/informacion\/wp-content\/uploads\/2016\/07\/fachada-artica.jpg 584w, https:\/\/www.delsofa.es\/informacion\/wp-content\/uploads\/2016\/07\/fachada-artica-300x135.jpg 300w, https:\/\/www.delsofa.es\/informacion\/wp-content\/uploads\/2016\/07\/fachada-artica-500x224.jpg 500w\" sizes=\"(max-width: 584px) 100vw, 584px\" \/><\/p>\n<p><strong>Te invitamos a conocer sus instalaciones.<\/strong><!--more--><\/p>\n<p style=\"text-align: justify;\">Situada en la <strong>Avenida Mart\u00ednez Velasco, 57-59 de la ciudad de Huesca<\/strong>. \u00c1rtica naci\u00f3 hace algo m\u00e1s de 40 a\u00f1os con el nombre de Muebles Alcubierre, desde entonces ofrece a sus clientes un amplio cat\u00e1logo de muebles para el hogar.<\/p>\n<p style=\"text-align: justify;\">Con un <strong>amplio horario comercial<\/strong>. De lunes a s\u00e1bado de 10 a 13.30 y de 17 a 20.30 horas. En sus instalaciones cuenta con una gran exposici\u00f3n de tapicer\u00eda. En ella encontrar\u00e1s, para comprobar la calidad y confortabilidad, algunos modelos a la venta en delsofa.es.<\/p>\n<p style=\"text-align: justify;\">Como se\u00f1alan en <a href=\"http:\/\/www.articatiendas.com\/\" target=\"_blank\">su web<\/a>, ofrecen a sus visitantes <strong>proyectos de decoraci\u00f3n y amueblamiento de hogar personalizados<\/strong>, que se ajustan a sus necesidades y gustos. Pide presupuesto sin compromiso y d\u00e9jate aconsejar por sus expertos profesionales.<\/p>\n<p style=\"text-align: justify;\">En su establecimiento encontrar\u00e1s muebles para el sal\u00f3n, dormitorios (principal, juvenil, de invitados), muebles auxiliares, art\u00edculos de decoraci\u00f3n, iluminaci\u00f3n, regalos para bodas, bautizos, comuniones, beb\u00e9s\u2026, textil (colchas, cojines, alfombras\u2026), aromas para el hogar, muebles de jard\u00edn, ba\u00f1os, cocina. Y como os hemos contado un <strong>amplio cat\u00e1logo de sillones, sof\u00e1s cama, sof\u00e1s, chaise longue<\/strong> y otros productos de tapicer\u00eda.<\/p>\n<h2>Tu tienda Delsof\u00e1 a un paso<\/h2>\n<p style=\"text-align: justify;\">En Delsof\u00e1 sabemos que comprar un sof\u00e1, sill\u00f3n de relax, sof\u00e1 cama\u2026 es una decisi\u00f3n meditada. A los clientes les gusta saber qu\u00e9 sensaci\u00f3n les aportar\u00e1 sentarse o acostarse en ellos. De ah\u00ed que en nuestra tienda online contamos con una <strong>red de establecimientos f\u00edsicos con m\u00e1s de 160 puntos<\/strong> de venta en toda Espa\u00f1a.<\/p>\n<p style=\"text-align: justify;\">Encontrar tu tienda oficial o distribuidor autorizado Delsof\u00e1 m\u00e1s cercano es muy sencillo. <strong>Accede a nuestro buscador en la web<\/strong> y encuentra tu punto de venta m\u00e1s cercano. Para ello visita la pesta\u00f1a de la esquina superior derecha con el texto \u201cTiendas de Sof\u00e1s\u201d.<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-4071 size-full\" title=\"Buscador tiendas Delsofa.es\" src=\"https:\/\/www.delsofa.es\/informacion\/wp-content\/uploads\/2014\/08\/buscador-alicante.jpg\" alt=\"Buscador tiendas Delsofa.es\" width=\"584\" height=\"619\" srcset=\"https:\/\/www.delsofa.es\/informacion\/wp-content\/uploads\/2014\/08\/buscador-alicante.jpg 584w, https:\/\/www.delsofa.es\/informacion\/wp-content\/uploads\/2014\/08\/buscador-alicante-283x300.jpg 283w\" sizes=\"(max-width: 584px) 100vw, 584px\" \/><\/p>\n<p style=\"text-align: justify;\">Al acceder a nuestro buscador encontrar\u00e1s un listado con todas las tiendas. Para facilitar la b\u00fasqueda ponemos a tu disposici\u00f3n un desplegable, donde <strong>puedes elegir tu provincia y provincias lim\u00edtrofes<\/strong> para encontrar las tiendas que tenemos en ellas.<\/p>\n<p style=\"text-align: justify;\">Una vez que te mostramos el listado de las tiendas en esas provincias. <strong>Solo debes hacer clic en el nombre del comercio. Al hacerlo te dirigimos a su ficha<\/strong>. En ella ver\u00e1s informaci\u00f3n como su direcci\u00f3n, tel\u00e9fono, email, web, perfiles sociales, localizaci\u00f3n en Google Maps, horario comercial. Adem\u00e1s puedes rellenar el formulario que encuentras al final y consultar\u00e1s tus dudas al personal de tienda. En la ficha tambi\u00e9n ponemos a tu disposici\u00f3n una herramienta que te sugiere la ruta en coche m\u00e1s r\u00e1pida para llegar desde el punto de origen que nos digas.<\/p>\n<p style=\"text-align: justify;\">Si necesitas m\u00e1s informaci\u00f3n sobre los productos a la venta, en exposici\u00f3n, tus tiendas m\u00e1s cercanas, tambi\u00e9n puedes llamar a nuestro personal de atenci\u00f3n al cliente. Te atienden de lunes a viernes de 8 a 20 horas en el <strong>tel\u00e9fono gratuito 900.701.086<\/strong>. Si no necesitas una respuesta inmediata, <strong>puedes dejar un comentario en esta entrada<\/strong> y te responderemos a la mayor brevedad posible. Gracias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOTA: Esta tienda ya no pertenece a la red de distribuidores de Colchones.es. Aqu\u00ed puedes encontrar nuestras tiendas f\u00edsicas en Huesca Este mes el viaje virtual para conocer las tiendas f\u00edsicas de Delsof\u00e1 nos lleva a la provincia de Huesca. &hellip; <a href=\"https:\/\/www.delsofa.es\/informacion\/artica-distribuidor-delsofa-huesca\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":4509,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[204],"tags":[1454,1420,1456,1455,1457],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c1rtica, distribuidor de Delsof\u00e1 en Huesca<\/title>\n<meta name=\"description\" content=\"En la tienda \u00c1rtica Huesca puedes probar los sof\u00e1s, sof\u00e1s cama, chaise longue, sillones... a la venta en Delsof\u00e1. Son distribuidores autorizados. Vis\u00edtalos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.delsofa.es\/informacion\/artica-distribuidor-delsofa-huesca\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00c1rtica, distribuidor de Delsof\u00e1 en Huesca\" \/>\n<meta name=\"twitter:description\" content=\"En la tienda \u00c1rtica Huesca puedes probar los sof\u00e1s, sof\u00e1s cama, chaise longue, sillones... a la venta en Delsof\u00e1. Son distribuidores autorizados. Vis\u00edtalos.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.delsofa.es\/informacion\/wp-content\/uploads\/2016\/07\/fachada-artica.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/www.twitter.com\/inmolber\" \/>\n<meta name=\"twitter:site\" content=\"@delsofaES\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Inma Molt\u00f3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.delsofa.es\/informacion\/#website\",\"url\":\"https:\/\/www.delsofa.es\/informacion\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.delsofa.es\/informacion\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.delsofa.es\/informacion\/artica-distribuidor-delsofa-huesca\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/www.delsofa.es\/informacion\/wp-content\/uploads\/2016\/07\/fachada-artica.jpg\",\"contentUrl\":\"https:\/\/www.delsofa.es\/informacion\/wp-content\/uploads\/2016\/07\/fachada-artica.jpg\",\"width\":584,\"height\":262},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.delsofa.es\/informacion\/artica-distribuidor-delsofa-huesca\/#webpage\",\"url\":\"https:\/\/www.delsofa.es\/informacion\/artica-distribuidor-delsofa-huesca\/\",\"name\":\"\u00c1rtica, distribuidor de Delsof\u00e1 en Huesca\",\"isPartOf\":{\"@id\":\"https:\/\/www.delsofa.es\/informacion\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.delsofa.es\/informacion\/artica-distribuidor-delsofa-huesca\/#primaryimage\"},\"datePublished\":\"2016-07-20T09:44:13+00:00\",\"dateModified\":\"2017-02-22T12:55:18+00:00\",\"author\":{\"@id\":\"https:\/\/www.delsofa.es\/informacion\/#\/schema\/person\/904d00808e282031a3b11f51524d259c\"},\"description\":\"En la tienda \u00c1rtica Huesca puedes probar los sof\u00e1s, sof\u00e1s cama, chaise longue, sillones... a la venta en Delsof\u00e1. Son distribuidores autorizados. Vis\u00edtalos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.delsofa.es\/informacion\/artica-distribuidor-delsofa-huesca\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.delsofa.es\/informacion\/artica-distribuidor-delsofa-huesca\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.delsofa.es\/informacion\/artica-distribuidor-delsofa-huesca\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.delsofa.es\/informacion\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c1rtica, distribuidor de Delsof\u00e1 en Huesca\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.delsofa.es\/informacion\/#\/schema\/person\/904d00808e282031a3b11f51524d259c\",\"name\":\"Inma Molt\u00f3\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.delsofa.es\/informacion\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6411caf208a31a6dd0c4c353341facb7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6411caf208a31a6dd0c4c353341facb7?s=96&d=mm&r=g\",\"caption\":\"Inma Molt\u00f3\"},\"description\":\"Soy periodista, community manager y formadora en redes sociales. Desde enero de 2013 escribo en el Blog Delsofa y actualmente tambi\u00e9n me encargo de su supervisi\u00f3n. Me encanta todo lo relacionado con la decoraci\u00f3n y el dise\u00f1o. Si quer\u00e9is saber m\u00e1s os dejo mi web: www.periodistasocialmedia.com\",\"sameAs\":[\"http:\/\/www.periodistasocialmedia.com\",\"https:\/\/twitter.com\/http:\/\/www.twitter.com\/inmolber\"],\"url\":\"https:\/\/www.delsofa.es\/informacion\/author\/inma\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c1rtica, distribuidor de Delsof\u00e1 en Huesca","description":"En la tienda \u00c1rtica Huesca puedes probar los sof\u00e1s, sof\u00e1s cama, chaise longue, sillones... a la venta en Delsof\u00e1. Son distribuidores autorizados. Vis\u00edtalos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.delsofa.es\/informacion\/artica-distribuidor-delsofa-huesca\/","twitter_card":"summary_large_image","twitter_title":"\u00c1rtica, distribuidor de Delsof\u00e1 en Huesca","twitter_description":"En la tienda \u00c1rtica Huesca puedes probar los sof\u00e1s, sof\u00e1s cama, chaise longue, sillones... a la venta en Delsof\u00e1. Son distribuidores autorizados. Vis\u00edtalos.","twitter_image":"https:\/\/www.delsofa.es\/informacion\/wp-content\/uploads\/2016\/07\/fachada-artica.jpg","twitter_creator":"@http:\/\/www.twitter.com\/inmolber","twitter_site":"@delsofaES","twitter_misc":{"Escrito por":"Inma Molt\u00f3","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.delsofa.es\/informacion\/#website","url":"https:\/\/www.delsofa.es\/informacion\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.delsofa.es\/informacion\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/www.delsofa.es\/informacion\/artica-distribuidor-delsofa-huesca\/#primaryimage","inLanguage":"es","url":"https:\/\/www.delsofa.es\/informacion\/wp-content\/uploads\/2016\/07\/fachada-artica.jpg","contentUrl":"https:\/\/www.delsofa.es\/informacion\/wp-content\/uploads\/2016\/07\/fachada-artica.jpg","width":584,"height":262},{"@type":"WebPage","@id":"https:\/\/www.delsofa.es\/informacion\/artica-distribuidor-delsofa-huesca\/#webpage","url":"https:\/\/www.delsofa.es\/informacion\/artica-distribuidor-delsofa-huesca\/","name":"\u00c1rtica, distribuidor de Delsof\u00e1 en Huesca","isPartOf":{"@id":"https:\/\/www.delsofa.es\/informacion\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.delsofa.es\/informacion\/artica-distribuidor-delsofa-huesca\/#primaryimage"},"datePublished":"2016-07-20T09:44:13+00:00","dateModified":"2017-02-22T12:55:18+00:00","author":{"@id":"https:\/\/www.delsofa.es\/informacion\/#\/schema\/person\/904d00808e282031a3b11f51524d259c"},"description":"En la tienda \u00c1rtica Huesca puedes probar los sof\u00e1s, sof\u00e1s cama, chaise longue, sillones... a la venta en Delsof\u00e1. Son distribuidores autorizados. Vis\u00edtalos.","breadcrumb":{"@id":"https:\/\/www.delsofa.es\/informacion\/artica-distribuidor-delsofa-huesca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.delsofa.es\/informacion\/artica-distribuidor-delsofa-huesca\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.delsofa.es\/informacion\/artica-distribuidor-delsofa-huesca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.delsofa.es\/informacion\/"},{"@type":"ListItem","position":2,"name":"\u00c1rtica, distribuidor de Delsof\u00e1 en Huesca"}]},{"@type":"Person","@id":"https:\/\/www.delsofa.es\/informacion\/#\/schema\/person\/904d00808e282031a3b11f51524d259c","name":"Inma Molt\u00f3","image":{"@type":"ImageObject","@id":"https:\/\/www.delsofa.es\/informacion\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/6411caf208a31a6dd0c4c353341facb7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6411caf208a31a6dd0c4c353341facb7?s=96&d=mm&r=g","caption":"Inma Molt\u00f3"},"description":"Soy periodista, community manager y formadora en redes sociales. Desde enero de 2013 escribo en el Blog Delsofa y actualmente tambi\u00e9n me encargo de su supervisi\u00f3n. Me encanta todo lo relacionado con la decoraci\u00f3n y el dise\u00f1o. Si quer\u00e9is saber m\u00e1s os dejo mi web: www.periodistasocialmedia.com","sameAs":["http:\/\/www.periodistasocialmedia.com","https:\/\/twitter.com\/http:\/\/www.twitter.com\/inmolber"],"url":"https:\/\/www.delsofa.es\/informacion\/author\/inma\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.delsofa.es\/informacion\/wp-json\/wp\/v2\/posts\/4508"}],"collection":[{"href":"https:\/\/www.delsofa.es\/informacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.delsofa.es\/informacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.delsofa.es\/informacion\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.delsofa.es\/informacion\/wp-json\/wp\/v2\/comments?post=4508"}],"version-history":[{"count":4,"href":"https:\/\/www.delsofa.es\/informacion\/wp-json\/wp\/v2\/posts\/4508\/revisions"}],"predecessor-version":[{"id":4615,"href":"https:\/\/www.delsofa.es\/informacion\/wp-json\/wp\/v2\/posts\/4508\/revisions\/4615"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.delsofa.es\/informacion\/wp-json\/wp\/v2\/media\/4509"}],"wp:attachment":[{"href":"https:\/\/www.delsofa.es\/informacion\/wp-json\/wp\/v2\/media?parent=4508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.delsofa.es\/informacion\/wp-json\/wp\/v2\/categories?post=4508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.delsofa.es\/informacion\/wp-json\/wp\/v2\/tags?post=4508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}